{"id":1651,"date":"2025-12-16T21:22:15","date_gmt":"2025-12-17T00:22:15","guid":{"rendered":"https:\/\/omniadc.com\/?p=1651"},"modified":"2025-12-16T21:22:17","modified_gmt":"2025-12-17T00:22:17","slug":"omnia-anuncia-construcao-de-seu-primeiro-data-center-sustentavel-no-ceara-desenvolvido-em-parceria-com-a-casa-dos-ventos","status":"publish","type":"post","link":"http:\/\/omniadc.com\/en\/omnia-anuncia-construcao-de-seu-primeiro-data-center-sustentavel-no-ceara-desenvolvido-em-parceria-com-a-casa-dos-ventos\/","title":{"rendered":"OMNIA anuncia constru\u00e7\u00e3o de seu primeiro Data Center sustent\u00e1vel, no Cear\u00e1, desenvolvido em parceria com a Casa dos Ventos"},"content":{"rendered":"<p class=\"has-text-align-center\"><br><em>Novo projeto de infraestrutura digital da Omnia, investida do Fundo Patria Infraestrutura V, prev\u00ea investimento de at\u00e9 US$ 2 bilh\u00f5es, capacidade de TI de 200 MW e opera\u00e7\u00e3o com energia 100% renov\u00e1vel e baix\u00edssimo consumo de \u00e1gua.<\/em><\/p>\n\n\n\n<p><strong>3 de Novembro de 2025 \u2013<\/strong> A <strong>Omnia<\/strong>, plataforma de Data Centers hiperescal\u00e1veis e investida do Fundo V de Infraestrutura do Patria Investimentos, anuncia hoje o seu primeiro projeto de Data Center sustent\u00e1vel de grande porte, desenvolvido em parceria com a <strong>Casa dos Ventos<\/strong>, refer\u00eancia em energias renov\u00e1veis e protagonista da transforma\u00e7\u00e3o energ\u00e9tica no Brasil. O an\u00fancio ocorre no momento em que o Conselho Nacional das Zonas de Processamento e Exporta\u00e7\u00e3o (CZPE) emitiu autoriza\u00e7\u00e3o para instala\u00e7\u00e3o do projeto.<\/p>\n\n\n\n<p>O <strong>Data Center Pec\u00e9m<\/strong> ser\u00e1 constru\u00eddo na Zona de Processamento de Exporta\u00e7\u00e3o (ZPE Cear\u00e1) do Complexo Industrial e Portu\u00e1rio do Porto do Pec\u00e9m (CIPP), e ter\u00e1 capacidade inicial de 200 MW de processamento (consumindo at\u00e9 300 MW de energia total), tornando-se assim um dos maiores Data Centers da Am\u00e9rica Latina, e o primeiro voltado \u00e0 exporta\u00e7\u00e3o, projetado para atender \u00e0s grandes empresas de tecnologia do mundo e suas demandas globais de Cloud e Intelig\u00eancia Artificial.<\/p>\n\n\n\n<p>Com in\u00edcio de constru\u00e7\u00e3o previsto ainda para este ano, e entrada em opera\u00e7\u00e3o prevista para o segundo semestre de 2027, o projeto receber\u00e1 da Omnia investimentos de at\u00e9 US$ 2 bilh\u00f5es para a constru\u00e7\u00e3o de sua infraestrutura, al\u00e9m de vultosos investimentos a serem trazidos por seu cliente \u00e2ncora, que ocupar\u00e1 toda a capacidade inicial do Data Center.<\/p>\n\n\n\n<p>O empreendimento utilizar\u00e1 energia 100% verde e renov\u00e1vel, proveniente de novos parques e\u00f3licos da Casa dos Ventos, dedicados ao projeto, refor\u00e7ando o compromisso com a transforma\u00e7\u00e3o energ\u00e9tica e a descarboniza\u00e7\u00e3o da economia global. O projeto conta ainda com sistema de refrigera\u00e7\u00e3o em ciclo fechado, o que possibilita um baix\u00edssimo consumo de \u00e1gua (30 m<sup>3<\/sup>\/dia), equivalente a cerca de 70 resid\u00eancias m\u00e9dias, sendo a maior parte voltada para consumo humano e predial, e apenas cerca de 10% desse total utilizado para a refrigera\u00e7\u00e3o, tornando o Data Center uma refer\u00eancia em efici\u00eancia h\u00eddrica e sustentabilidade.<\/p>\n\n\n\n<p>\u201cEstamos entusiasmados com o lan\u00e7amento do primeiro Data Center da Omnia, principalmente por se tratar de um empreendimento que reflete o nosso compromisso com o desenvolvimento de infraestrutura com foco na sustentabilidade, gerando desenvolvimento econ\u00f4mico, tecnol\u00f3gico e social para o pa\u00eds\u201d, afirma Rodrigo Abreu, CEO da Omnia e Operating Partner do P\u00e1tria Investimentos. \u201cO Data Center Pec\u00e9m representa um marco importante para a ind\u00fastria digital no Brasil, possibilitando que o pa\u00eds assuma um protagonismo global na atra\u00e7\u00e3o de investimentos para a economia do conhecimento, servindo de forma competitiva e sustent\u00e1vel novas demandas como \u00e9 o caso da Intelig\u00eancia Artificial\u201d.<\/p>\n\n\n\n<p>O projeto marca o in\u00edcio do Polo de Data Centers do Pec\u00e9m, iniciativa idealizada pela Casa dos Ventos, e que conta com a lideran\u00e7a da Omnia no desenvolvimento e implanta\u00e7\u00e3o de seu primeiro projeto, posicionando o Cear\u00e1 como um dos principais polos tecnol\u00f3gicos e energ\u00e9ticos da Am\u00e9rica Latina. \u201cA parceria entre Casa dos Ventos e Omnia \u00e9 pioneira no \u00e2mbito do surgimento dos megadacenters no nosso pa\u00eds. O Brasil tem os atributos certos para liderar esse mercado: matriz energ\u00e9tica renov\u00e1vel, conectividade robusta e capital humano qualificado. Esta \u00e9 uma oportunidade concreta para exportar servi\u00e7os de alto valor agregado e acelerar a transforma\u00e7\u00e3o energ\u00e9tica\u201d, comenta Lucas Araripe, Diretor-Executivo da Casa dos Ventos.<\/p>\n\n\n\n<p><strong>Projeto sustent\u00e1vel com desenvolvimento para o Brasil e para a regi\u00e3o<\/strong><\/p>\n\n\n\n<p>Localizado a apenas 40 km da capital Fortaleza, o projeto se beneficia da infraestrutura do CIPP e da ZPE Cear\u00e1, e ser\u00e1 conectado diretamente aos cabos submarinos de fibra \u00f3ptica internacionais que chegam a Fortaleza. Essa estrutura garante acesso \u00e0s principais rotas internacionais de dados que conectam o Brasil \u00e0 Am\u00e9rica do Norte, Europa, \u00c1frica e demais pa\u00edses da Am\u00e9rica Latina, consolidando o Brasil como exportador de servi\u00e7os digitais de alto valor agregado. Al\u00e9m de sua relev\u00e2ncia tecnol\u00f3gica, o projeto trar\u00e1 impactos positivos para a economia, gerando empregos diretos e indiretos, impulsionando a conectividade regional e atraindo investimentos estrangeiros. S\u00e3o previstos tamb\u00e9m investimentos em pesquisa e desenvolvimento de tecnologias de ponta, como intelig\u00eancia artificial e computa\u00e7\u00e3o de alto desempenho, al\u00e9m de projetos de impacto socioambiental positivo nas \u00e1reas de educa\u00e7\u00e3o, forma\u00e7\u00e3o de m\u00e3o de obra qualificada e recursos h\u00eddricos, em discuss\u00e3o com as comunidades locais e regionais por meio da intera\u00e7\u00e3o com os governos estadual e municipal.<\/p>\n\n\n\n<p>Como l\u00edder em investimentos em infraestrutura na America Latina, o Patria criou e desenvolveu uma das maiores plataformas de data centers da Am\u00e9rica Latina, a Odata, desinvestida com sucesso em 2023. Com a Omnia, o Patria reafirma seu compromisso em liderar iniciativas de alto impacto no setor de infraestrutura digital sustent\u00e1vel em ampliar os investimentos no desenvolvimento de projetos no Brasil e demais pa\u00edses da Am\u00e9rica Latina, como Chile, M\u00e9xico e Col\u00f4mbia.<\/p>\n\n\n\n<p><strong>Sobre a OMNIA:&nbsp;<br><\/strong>A OMNIA \u00e9 uma plataforma de data centers hiperescal\u00e1veis criada para atender \u00e0 crescente demanda por capacidade e efici\u00eancia da ind\u00fastria de infraestrutura digital, especialmente impulsionada pelas tecnologias de cloud, intelig\u00eancia artificial (IA) e computa\u00e7\u00e3o de alto desempenho. Investida de fundos do P\u00e1tria Investimentos, a OMNIA possui foco no desenvolvimento de Data Centers de grande escala na Am\u00e9rica Latina, oferecendo infraestrutura de ponta capaz de suportar cargas computacionais intensivas. Seu primeiro projeto, o Data Center Pec\u00e9m, ser\u00e1 o maior empreendimento hyperscale da regi\u00e3o, com 200 MW de capacidade. O projeto prioriza a sustentabilidade, com opera\u00e7\u00e3o prevista para ser 100% movida a energia renov\u00e1vel em parceria com a Casa dos Ventos, al\u00e9m de solu\u00e7\u00f5es avan\u00e7adas de resfriamento de baixo consumo h\u00eddrico, com circuitos fechados de reuso de \u00e1gua. A empresa ir\u00e1 ajudar a consolidar a Am\u00e9rica Latina como polo estrat\u00e9gico da nova economia digital, atendendo a demandas globais de tecnologia.<\/p>\n\n\n\n<p><strong>Sobre a Casa dos Ventos<\/strong><\/p>\n\n\n\n<p>Somos refer\u00eancia em energia renov\u00e1vel e protagonista na transforma\u00e7\u00e3o energ\u00e9tica do Brasil. Com quase duas d\u00e9cadas de atua\u00e7\u00e3o, temos conhecimento em todos os elos da cadeia do setor e trabalhamos para que nossos clientes tenham redu\u00e7\u00e3o de custos e atinjam suas metas de emiss\u00e3o de forma eficiente e sustent\u00e1vel.<\/p>\n\n\n\n<p>Para avan\u00e7ar em nossa posi\u00e7\u00e3o de relev\u00e2ncia no setor, possu\u00edmos, conjuntamente com empresas do grupo, o maior portf\u00f3lio de projetos e\u00f3licos e solares do Pa\u00eds, com mais de 60 GW de projetos desenvolvidos ou em desenvolvimento por empresas do grupo.<\/p>\n\n\n\n<p>Aceleramos nosso crescimento por meio da entrada da TotalEnergies como acionista, uma das maiores empresas de energia do mundo, e nos tornamos o ve\u00edculo exclusivo de renov\u00e1veis da multinacional no pa\u00eds.<\/p>\n\n\n\n<p>Somos signat\u00e1rios do Pacto Global da ONU e trabalhamos de forma alinhada aos 17 Objetivos de Desenvolvimento Sustent\u00e1vel (ODS) e \u00e0s melhores pr\u00e1ticas de ESG; preservamos os biomas locais e desenvolvemos projetos sociais nas comunidades em que estamos presentes, de modo a contribuirmos para impulsionar o Brasil rumo a uma economia de baixo carbono.<\/p>\n\n\n\n<p><strong>Sobre o Patria Investimentos<\/strong>\u202f&nbsp;<\/p>\n\n\n\n<p>O Patria \u00e9 uma gestora global de ativos alternativos, l\u00edder na Am\u00e9rica Latina e com relevante presen\u00e7a na Europa atrav\u00e9s da uma extensa rede de relacionamentos com investidores. A nossa presen\u00e7a local combina l\u00edderes de investimento, especialistas setoriais, gestores de empresas e relacionamentos estrat\u00e9gicos, permitindo-nos identificar oportunidades de investimento atraentes, acess\u00edveis apenas a quem possui profici\u00eancia local. Com 37 anos de experi\u00eancia e R$ 266 bilh\u00f5es em ativos sob gest\u00e3o, entregamos consistentemente retornos atraentes atrav\u00e9s de investimentos de longo prazo, ao mesmo tempo em que promovemos o desenvolvimento inclusivo e sustent\u00e1vel nas regi\u00f5es onde operamos.\u202f\u202f&nbsp;<\/p>\n\n\n\n<p>Classes de Ativos: Private Equity, Solutions, Cr\u00e9dito, Real Estate, Infraestrutura e A\u00e7\u00f5es P\u00fablicas\u202f\u202f&nbsp;<\/p>\n\n\n\n<p>Setores Principais: Agroneg\u00f3cio, Energia, Sa\u00fade, Log\u00edstica e Transportes, Alimentos e Bebidas e Servi\u00e7os Digitais e de Tecnologia\u202f\u202f&nbsp;&nbsp;<\/p>\n\n\n\n<p>Regi\u00f5es de Investimento: Am\u00e9rica Latina, Europa e EUA<\/p>","protected":false},"excerpt":{"rendered":"<p>Novo projeto de infraestrutura digital da Omnia, investida do Fundo Patria Infraestrutura V, prev\u00ea investimento de at\u00e9 US$ 2 bilh\u00f5es, capacidade de TI de 200 MW e opera\u00e7\u00e3o com energia 100% renov\u00e1vel e baix\u00edssimo consumo de \u00e1gua. 3 de Novembro de 2025 \u2013 A Omnia, plataforma de Data Centers hiperescal\u00e1veis e investida do Fundo V [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1652,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-1651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"http:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/posts\/1651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/comments?post=1651"}],"version-history":[{"count":1,"href":"http:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/posts\/1651\/revisions"}],"predecessor-version":[{"id":1653,"href":"http:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/posts\/1651\/revisions\/1653"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/media\/1652"}],"wp:attachment":[{"href":"http:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/media?parent=1651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/categories?post=1651"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/tags?post=1651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}