{"id":1737,"date":"2026-01-26T05:27:24","date_gmt":"2026-01-26T08:27:24","guid":{"rendered":"https:\/\/omniadc.com\/?p=1737"},"modified":"2026-01-26T05:32:19","modified_gmt":"2026-01-26T08:32:19","slug":"obras-do-data-center-do-tiktok-no-ceara-sao-iniciadas","status":"publish","type":"post","link":"https:\/\/omniadc.com\/en\/obras-do-data-center-do-tiktok-no-ceara-sao-iniciadas\/","title":{"rendered":"Obras do data center do TikTok no Cear\u00e1 s\u00e3o iniciadas"},"content":{"rendered":"<p>As obras do data center do <strong>TikTok<\/strong> no Complexo do Pec\u00e9m, em Caucaia (CE), foram iniciadas no come\u00e7o de janeiro. A informa\u00e7\u00e3o foi confirmada por <strong>Rodrigo Abreu<\/strong>, CEO da <strong>OMNIA<\/strong>, respons\u00e1vel pelo desenvolvimento do projeto, que tem a <strong>Casa dos Ventos<\/strong> como parceira no fornecimento de energia renov\u00e1vel.<\/p>\n\n\n\n<p>Nesta fase inicial, as atividades incluem supress\u00e3o vegetal e terraplanagem. O cronograma prev\u00ea a entrega do primeiro data hall em 2027. Ao considerar todas as etapas de expans\u00e3o, o empreendimento tem potencial para se tornar o maior investimento privado j\u00e1 realizado no Brasil.<\/p>\n\n\n\n<p><strong>Leia a mat\u00e9ria completa:<\/strong> <a href=\"https:\/\/diariodonordeste.verdesmares.com.br\/opiniao\/colunistas\/victor-ximenes\/obra-do-data-center-do-tiktok-no-ceara-e-iniciada-1.3732274\" target=\"_blank\" rel=\"noopener\">https:\/\/diariodonordeste.verdesmares.com.br\/opiniao\/colunistas\/victor-ximenes\/obra-do-data-center-do-tiktok-no-ceara-e-iniciada-1.3732274<\/a><\/p>\n\n\n\n<p><strong>Foto:<\/strong>&nbsp;Fabiane de Paula<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>As obras do data center do TikTok no Complexo do Pec\u00e9m, em Caucaia (CE), foram iniciadas no come\u00e7o de janeiro. A informa\u00e7\u00e3o foi confirmada por Rodrigo Abreu, CEO da OMNIA, respons\u00e1vel pelo desenvolvimento do projeto, que tem a Casa dos Ventos como parceira no fornecimento de energia renov\u00e1vel. Nesta fase inicial, as atividades incluem supress\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-na-midia"],"_links":{"self":[{"href":"https:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/posts\/1737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/comments?post=1737"}],"version-history":[{"count":1,"href":"https:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/posts\/1737\/revisions"}],"predecessor-version":[{"id":1739,"href":"https:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/posts\/1737\/revisions\/1739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/media\/1741"}],"wp:attachment":[{"href":"https:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/media?parent=1737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/categories?post=1737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/omniadc.com\/en\/wp-json\/wp\/v2\/tags?post=1737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}